{"id":70,"date":"2021-07-05T13:05:52","date_gmt":"2021-07-05T13:05:52","guid":{"rendered":"https:\/\/adipson-studio.com\/?p=70"},"modified":"2022-06-09T06:47:20","modified_gmt":"2022-06-09T06:47:20","slug":"un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone","status":"publish","type":"post","link":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/","title":{"rendered":"3 Geeks&#8230;un jeu fran\u00e7ais plus connu aux USA et aux Royaume Unis que sur l&rsquo;Hexagone&#8230;"},"content":{"rendered":"<h1>Le jeu 3 Geeks souffre d&rsquo;une sorte de mal\u00e9diction depuis sa sortie en f\u00e9vrier 2019&#8230;100 % fran\u00e7ais et destin\u00e9 \u00e0 la base que pour un public de joueurs francophones, le jeu est le plus souvent jou\u00e9 par des am\u00e9ricains ou des anglais&#8230;et l\u00e0 c&rsquo;est le drame&#8230;<\/h1>\n<h2>Un jeu Frenchy devenu un OVNI outre-manche<\/h2>\n<p>Quand vous sortez un jeu totalement en fran\u00e7ais, adapt\u00e9 pour un public de joueurs fran\u00e7ais trentenaires, quarantenaires ou cinquantenaires, et que ce sont des anglais qui ach\u00e8tent le plus souvent votre jeu&#8230;cela devient forc\u00e9ment vecteur de quelques soucis de compr\u00e9hension&#8230;<\/p>\n<p>Avec un humour largement bas\u00e9 sur des r\u00e9f\u00e9rences de chansons fran\u00e7aises, de publicit\u00e9s ou de nos films fran\u00e7ais cultes, comme les 3 Fr\u00e8res des Inconnus pour ne citer que lui, on se retrouve tr\u00e8s vite devant un floril\u00e8ge de joueurs qui, lorsqu&rsquo;ils ne sont absolument pas francophones, ne savourent pas le jeu comme il se devrait. Mais certains essaient quand m\u00eame et c&rsquo;est tout \u00e0 leur honneur&#8230;so thanks you !<\/p>\n<p>Mais <u>il ne faut pas oublier qu&rsquo;\u00e0 la base, le jeu est destin\u00e9 uniquement qu&rsquo;aux joueurs fran\u00e7ais.<\/u><br \/>\nAyant eue de nombreuses demandes pour proposer une version traduite en Anglais de ce jeu lors de sa mise en ligne dans la boutique de <a href=\"https:\/\/store.steampowered.com\/app\/1023410\/3_GEEKS\/?l=french\" target=\"_blank\" rel=\"noopener\">Steam<\/a>, Adipson Studio a donc fait appel \u00e0 un traducteur anglais pour r\u00e9aliser les traductions de tous les dialogues&#8230;<br \/>\nMais la traduction n&rsquo;\u00e9tait pas au niveau estim\u00e9. Ajoutez donc un jeu mal traduit en anglais, adoptant un humour tr\u00e8s fran\u00e7ais destin\u00e9 aux fran\u00e7ais et vous avez <b>la recette miracle du jeu le plus incompr\u00e9hensible du domaine du point and click pour les anglophones&#8230;<\/b><\/p>\n<p>Certains iront quand m\u00eame, et courageusement, relever le d\u00e9fit de finir le jeu complet, et de se filmer pendant le gameplay plus de 4 heures&#8230; Si si ! C&rsquo;est v\u00e9ridique ! <b><\/b><\/p>\n<p><b>Voici ci-dessous la premi\u00e8re vid\u00e9o (sur 4) de cet acte quasi suicidaire d&rsquo;un anglophone essayant d&rsquo;avancer dans 3 Geeks&#8230;<br \/>\n<\/b>Une tr\u00e8s belle occasion d&rsquo;ailleurs de contempler le gameplay du jeu avant de vous d\u00e9cider de peut-\u00eatre l&rsquo;acheter pour vous lancer dans l&rsquo;aventure&#8230;<b><\/b><\/p>\n<p><b><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/CEL_0rKBTGU\" width=\"100%\" height=\"615\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><br \/>\n<\/b><\/p>\n<h2>Une nouvelle ligne \u00e9ditoriale pour les prochains projets<\/h2>\n<p>Cette catastrophe linguistique nous a donc donn\u00e9 une s\u00e9rieuse envie : celle de ne plus proposer de versions traduites en anglais pour nos prochaines r\u00e9alisations, \u00e0 moins de trouver un anglais francophone plut\u00f4t qu&rsquo;un fran\u00e7ais anglophone pour le travail sur la traduction.<\/p>\n<p>Mais ne pas proposer de version anglaises pour des jeux, alors que ce ne sont que les anglophones qui sont attir\u00e9s par nos titres n&rsquo;est-il pas \u00e0 vocation de se tirer une balle dans le pied ?<\/p>\n<p>Et bien c&rsquo;est ici qu&rsquo;intervient toute la subtilit\u00e9 de nos futurs projets&#8230;Des jeux qui se joueront dans toutes les langues, sans traduction&#8230;<br \/>\nVous d\u00e9couvrirez <b>\u00e0 partir de janvier 2021<\/b> le tout nouveau jeu du Studio Adipson adoptant ce concept&#8230;<\/p>\n<p><strong>edit le 17\/05\/2022 :<\/strong>\u00a0 <em>Ce jeu est sorti et se trouve donc \u00eatre <a href=\"https:\/\/adipson-studio.com\/index.php\/category\/grandma-badass\/\" target=\"_blank\" rel=\"noopener\">GrandMa Badass<\/a><\/em><\/p>\n<h2>En attendant, si vous \u00eates Fran\u00e7ais, soutenez les ind\u00e9 de votre nation !<\/h2>\n<p>Si vous \u00eates fran\u00e7ais, que vous avez du temps \u00e0 perdre pendant le confinement et un investissement incroyable de 8 euros \u00e0 faire pour soutenir un d\u00e9veloppeur ind\u00e9pendant de jeux vid\u00e9o fran\u00e7ais&#8230;vous pouvez toujours acheter le jeu 3 GEEKS ci-dessous !<br \/>\nD&rsquo;avance merci !<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/store.steampowered.com\/widget\/1023410\/\" width=\"100%\" height=\"190\" frameborder=\"0\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p><strong>PS 2 : il a \u00e9t\u00e9 d\u00e9cid\u00e9 en mai 2022 de passer 3 Geeks sur Steam en version assum\u00e9e 100% Gauloise.<\/strong><br \/>\nEn retirant donc le libell\u00e9 traduit en anglais pour ne le destiner qu&rsquo;au public fran\u00e7ais qui reste la cible prioritaire du jeu totalement adapt\u00e9 \u00e0 sa culture.<br \/>\nUne version Remasteris\u00e9e du jeu sera peut-\u00eatre envisag\u00e9e \u00e0 l&rsquo;avenir pour une adaptation plus \u00ab\u00a0internationalement politiquement correcte\u00a0\u00bb&#8230;<br \/>\nMais ce n&rsquo;est pas pour aujourd&rsquo;hui, le studio travaillant sur GrandMa Badass depuis 2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le jeu 3 Geeks souffre d&rsquo;une sorte de mal\u00e9diction depuis sa sortie en f\u00e9vrier 2019&#8230;100 % fran\u00e7ais et destin\u00e9 \u00e0 la base que pour un public de joueurs francophones, le jeu est le plus souvent jou\u00e9 par des am\u00e9ricains ou des anglais&#8230;et l\u00e0 c&rsquo;est le drame&#8230; Un jeu Frenchy devenu un OVNI outre-manche Quand vous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":71,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,6,3,4],"tags":[],"class_list":["post-70","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3-geeks","category-le-saviez-vous","category-presse","category-videos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3 Geeks...un jeu fran\u00e7ais plus connu aux USA et aux Royaume Unis que sur l&#039;Hexagone... - Adipson WebAgency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 Geeks...un jeu fran\u00e7ais plus connu aux USA et aux Royaume Unis que sur l&#039;Hexagone... - Adipson WebAgency\" \/>\n<meta property=\"og:description\" content=\"Le jeu 3 Geeks souffre d&rsquo;une sorte de mal\u00e9diction depuis sa sortie en f\u00e9vrier 2019&#8230;100 % fran\u00e7ais et destin\u00e9 \u00e0 la base que pour un public de joueurs francophones, le jeu est le plus souvent jou\u00e9 par des am\u00e9ricains ou des anglais&#8230;et l\u00e0 c&rsquo;est le drame&#8230; Un jeu Frenchy devenu un OVNI outre-manche Quand vous [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/\" \/>\n<meta property=\"og:site_name\" content=\"Adipson WebAgency\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-05T13:05:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-09T06:47:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adipson-studio.com\/wp-content\/uploads\/2021\/08\/uk2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"852\" \/>\n\t<meta property=\"og:image:height\" content=\"318\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Adipson Studio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adipson Studio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\\\/\"},\"author\":{\"name\":\"Adipson Studio\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#\\\/schema\\\/person\\\/5d13be29716904a3364d6073994ed481\"},\"headline\":\"3 Geeks&#8230;un jeu fran\u00e7ais plus connu aux USA et aux Royaume Unis que sur l&rsquo;Hexagone&#8230;\",\"datePublished\":\"2021-07-05T13:05:52+00:00\",\"dateModified\":\"2022-06-09T06:47:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\\\/\"},\"wordCount\":676,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adipson-studio.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/uk2.jpg\",\"articleSection\":[\"3 Geeks\",\"Le saviez-vous ?\",\"Presse\",\"Vid\u00e9os\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\\\/\",\"url\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\\\/\",\"name\":\"3 Geeks...un jeu fran\u00e7ais plus connu aux USA et aux Royaume Unis que sur l'Hexagone... - Adipson WebAgency\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adipson-studio.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/uk2.jpg\",\"datePublished\":\"2021-07-05T13:05:52+00:00\",\"dateModified\":\"2022-06-09T06:47:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adipson-studio.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/uk2.jpg\",\"contentUrl\":\"https:\\\/\\\/adipson-studio.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/uk2.jpg\",\"width\":852,\"height\":318},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/adipson-studio.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3 Geeks&#8230;un jeu fran\u00e7ais plus connu aux USA et aux Royaume Unis que sur l&rsquo;Hexagone&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#website\",\"url\":\"https:\\\/\\\/adipson-studio.com\\\/\",\"name\":\"Adipson WebAgency\",\"description\":\"Votre partenaire web depuis plus de 20 ans\",\"publisher\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adipson-studio.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#organization\",\"name\":\"Adipson WebAgency\",\"url\":\"https:\\\/\\\/adipson-studio.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adipson-studio.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logosite.png\",\"contentUrl\":\"https:\\\/\\\/adipson-studio.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logosite.png\",\"width\":283,\"height\":40,\"caption\":\"Adipson WebAgency\"},\"image\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#\\\/schema\\\/person\\\/5d13be29716904a3364d6073994ed481\",\"name\":\"Adipson Studio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ed85b4921ea2a5e59d63b240be84577f053b7523b3b651b34c20439bc159222?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ed85b4921ea2a5e59d63b240be84577f053b7523b3b651b34c20439bc159222?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ed85b4921ea2a5e59d63b240be84577f053b7523b3b651b34c20439bc159222?s=96&d=mm&r=g\",\"caption\":\"Adipson Studio\"},\"sameAs\":[\"https:\\\/\\\/adipson-studio.com\"],\"url\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/author\\\/romualdserrado_jt4cyldi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 Geeks...un jeu fran\u00e7ais plus connu aux USA et aux Royaume Unis que sur l'Hexagone... - Adipson WebAgency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/","og_locale":"fr_FR","og_type":"article","og_title":"3 Geeks...un jeu fran\u00e7ais plus connu aux USA et aux Royaume Unis que sur l'Hexagone... - Adipson WebAgency","og_description":"Le jeu 3 Geeks souffre d&rsquo;une sorte de mal\u00e9diction depuis sa sortie en f\u00e9vrier 2019&#8230;100 % fran\u00e7ais et destin\u00e9 \u00e0 la base que pour un public de joueurs francophones, le jeu est le plus souvent jou\u00e9 par des am\u00e9ricains ou des anglais&#8230;et l\u00e0 c&rsquo;est le drame&#8230; Un jeu Frenchy devenu un OVNI outre-manche Quand vous [&hellip;]","og_url":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/","og_site_name":"Adipson WebAgency","article_published_time":"2021-07-05T13:05:52+00:00","article_modified_time":"2022-06-09T06:47:20+00:00","og_image":[{"width":852,"height":318,"url":"https:\/\/adipson-studio.com\/wp-content\/uploads\/2021\/08\/uk2.jpg","type":"image\/jpeg"}],"author":"Adipson Studio","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Adipson Studio","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/#article","isPartOf":{"@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/"},"author":{"name":"Adipson Studio","@id":"https:\/\/adipson-studio.com\/#\/schema\/person\/5d13be29716904a3364d6073994ed481"},"headline":"3 Geeks&#8230;un jeu fran\u00e7ais plus connu aux USA et aux Royaume Unis que sur l&rsquo;Hexagone&#8230;","datePublished":"2021-07-05T13:05:52+00:00","dateModified":"2022-06-09T06:47:20+00:00","mainEntityOfPage":{"@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/"},"wordCount":676,"commentCount":0,"publisher":{"@id":"https:\/\/adipson-studio.com\/#organization"},"image":{"@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/#primaryimage"},"thumbnailUrl":"https:\/\/adipson-studio.com\/wp-content\/uploads\/2021\/08\/uk2.jpg","articleSection":["3 Geeks","Le saviez-vous ?","Presse","Vid\u00e9os"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/","url":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/","name":"3 Geeks...un jeu fran\u00e7ais plus connu aux USA et aux Royaume Unis que sur l'Hexagone... - Adipson WebAgency","isPartOf":{"@id":"https:\/\/adipson-studio.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/#primaryimage"},"image":{"@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/#primaryimage"},"thumbnailUrl":"https:\/\/adipson-studio.com\/wp-content\/uploads\/2021\/08\/uk2.jpg","datePublished":"2021-07-05T13:05:52+00:00","dateModified":"2022-06-09T06:47:20+00:00","breadcrumb":{"@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/#primaryimage","url":"https:\/\/adipson-studio.com\/wp-content\/uploads\/2021\/08\/uk2.jpg","contentUrl":"https:\/\/adipson-studio.com\/wp-content\/uploads\/2021\/08\/uk2.jpg","width":852,"height":318},{"@type":"BreadcrumbList","@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/un-jeu-francais-plus-connu-aux-usa-et-aux-royaume-unis-que-sur-lhexagone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/adipson-studio.com\/"},{"@type":"ListItem","position":2,"name":"3 Geeks&#8230;un jeu fran\u00e7ais plus connu aux USA et aux Royaume Unis que sur l&rsquo;Hexagone&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/adipson-studio.com\/#website","url":"https:\/\/adipson-studio.com\/","name":"Adipson WebAgency","description":"Votre partenaire web depuis plus de 20 ans","publisher":{"@id":"https:\/\/adipson-studio.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adipson-studio.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/adipson-studio.com\/#organization","name":"Adipson WebAgency","url":"https:\/\/adipson-studio.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adipson-studio.com\/#\/schema\/logo\/image\/","url":"https:\/\/adipson-studio.com\/wp-content\/uploads\/2024\/08\/logosite.png","contentUrl":"https:\/\/adipson-studio.com\/wp-content\/uploads\/2024\/08\/logosite.png","width":283,"height":40,"caption":"Adipson WebAgency"},"image":{"@id":"https:\/\/adipson-studio.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/adipson-studio.com\/#\/schema\/person\/5d13be29716904a3364d6073994ed481","name":"Adipson Studio","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2ed85b4921ea2a5e59d63b240be84577f053b7523b3b651b34c20439bc159222?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ed85b4921ea2a5e59d63b240be84577f053b7523b3b651b34c20439bc159222?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ed85b4921ea2a5e59d63b240be84577f053b7523b3b651b34c20439bc159222?s=96&d=mm&r=g","caption":"Adipson Studio"},"sameAs":["https:\/\/adipson-studio.com"],"url":"https:\/\/adipson-studio.com\/index.php\/author\/romualdserrado_jt4cyldi\/"}]}},"_links":{"self":[{"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/posts\/70","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/comments?post=70"}],"version-history":[{"count":6,"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/posts\/70\/revisions"}],"predecessor-version":[{"id":234,"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/posts\/70\/revisions\/234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/media\/71"}],"wp:attachment":[{"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/media?parent=70"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/categories?post=70"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/tags?post=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}