{"id":83,"date":"2021-07-05T13:18:49","date_gmt":"2021-07-05T13:18:49","guid":{"rendered":"https:\/\/adipson-studio.com\/?p=83"},"modified":"2021-08-05T13:27:00","modified_gmt":"2021-08-05T13:27:00","slug":"3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30","status":"publish","type":"post","link":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/","title":{"rendered":"3Geeks class\u00e9 humoristiquement et \u00e0 notre initiative PEGI 30"},"content":{"rendered":"<h1>Nous allons vous d\u00e9voiler pourquoi, m\u00eame si cet \u00e2ge l\u00e9gal n&rsquo;existe pas officiellement chez le label, le jeu 3 GEEKS pourrait \u00eatre classifi\u00e9 PEGI 30&#8230;<\/h1>\n<p>Le label PEGI ne d\u00e9passe pas l&rsquo;\u00e2ge de 18 ans, \u00e2ge l\u00e9gal o\u00f9 s&rsquo;arr\u00eatent toutes les limites officielles. Mais chez Adipson Studio nous allons plus loin en imaginant qu&rsquo;il pourrait exister une interdiction aux -30 ans&#8230;Et c&rsquo;est exactement l&rsquo;\u00e2ge minimum qu&rsquo;il faudrait pour comprendre et savourer pleinement ce jeu&#8230;Explications.<\/p>\n<h3>3 GEEKS un jeu et d\u00e9fis personnel avant tout<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-84 alignleft\" src=\"https:\/\/adipson-studio.com\/wp-content\/uploads\/2021\/08\/minitel.jpg\" alt=\"\" width=\"260\" height=\"195\" \/>Ce jeu est un condens\u00e9 de tout ce que d\u00e9testera un jeune gamer de cette nouvelle g\u00e9n\u00e9ration. Il exploite une sorte d&rsquo;\u00e2me indissociable des ann\u00e9es 80, de son ambiance jusqu&rsquo;aux trailers et aux vid\u00e9os made in fa\u00e7on Vintage.<b> 3 Geeks est en fait un jeu avec des r\u00e9f\u00e9rences que seuls leurs parents pourraient comprendre et appr\u00e9cier pleinement.<\/b><\/p>\n<p>Plus qu&rsquo;un simple jeu en 2D rendant hommage aux productions des point and click des ann\u00e9es 80 et 90 tout en \u00e9vitant de coller au traditionnel style \u00e0 la mode du pixel Art, 3 GEEKS est en fait un jeu personnel qui clos un d\u00e9fis tout autant personnel, qui se moque des quand dira-t-on et des propos vindicatifs \u00e0 son encontre lorsqu&rsquo;il n&rsquo;a pas \u00e9t\u00e9 jou\u00e9 du d\u00e9but \u00e0 la fin et surtout par quelqu&rsquo;un qui ne peut pas comprendre son message et appr\u00e9cier son style humoristique et ses r\u00e9f\u00e9rences cin\u00e9matographiques et ludiques \u00e0 cause d&rsquo;un trop jeune \u00e2ge.<\/p>\n<p>Le fait que son cr\u00e9ateur et votre serviteur, l&rsquo;ait termin\u00e9 compl\u00e8tement alors qu&rsquo;il trainait dans un coin de sa t\u00eate depuis plus de 40 ans est une victoire et m\u00eame la principale victoire.<\/p>\n<p>Alors si en plus derri\u00e8re cela il plait au minimum \u00e0 1 personne o\u00f9 qu&rsquo;il en amuse plusieurs centaines, ce n&rsquo;est que du bonus.<\/p>\n<h3>Pourquoi 3 GEEKS devrait \u00eatre class\u00e9 PEGI 30 ?<\/h3>\n<p>Il ne peut absolument pas \u00eatre compris par un joueur de nouvelle g\u00e9n\u00e9ration, qui serait n\u00e9 apr\u00e8s 1990. La raison est simple puisque ce jeu base toute son intrigue, ses r\u00e9f\u00e9rences et ses \u00e9nigmes autour de ce qui existait entre les ann\u00e9es 80 et 99. Que ce soit des r\u00e9f\u00e9rences au minitel, \u00e0 des films cultes des ann\u00e9es 90 comme les 3 Fr\u00e8res avec les inconnus ou encore plus proche cependant la pub Kinder Bueno de 2009.<\/p>\n<p>Il ne peut toucher que deux styles de joueurs. Les fans de point and click qui ont ador\u00e9 des r\u00e9f\u00e9rences comme <b>Monkey Island, Day of Tentacle, Maniac Mansion ou encore les jeux Lucas Arts <\/b>et ceux qui ont connus les ann\u00e9es 80 et 90&#8230;<\/p>\n<p>Certes cela r\u00e9duit \u00e9norm\u00e9ment la cible de joueurs, mais il ne faut pas occulter le fait que ce jeu est mis \u00e0 disposition du tout public, alors qu&rsquo;il n&rsquo;\u00e9tait \u00e0 l&rsquo;origine que la conclusion d&rsquo;un d\u00e9fis personnel qui est n\u00e9 en 1984 autour d&rsquo;un commodore 64.<\/p>\n<h3>Ne perdez peut-\u00eatre pas votre temps \u00e0 jouer \u00e0 3 GEEKS, ni m\u00eame \u00e0 la D\u00e9mo gratuite\u00a0 si&#8230;<\/h3>\n<ul>\n<li>Vous \u00eates n\u00e9 apr\u00e8s 1990<\/li>\n<li>Vous n&rsquo;avez m\u00eame pas esquiss\u00e9 un sourire \u00e0 la diffusion du film Les 3 Fr\u00e8res de 1995 avec les Inconnus<\/li>\n<li>Si vous ne comprenez rien \u00e0 la s\u00e9rie The Big Bang Theory<\/li>\n<li>Si vous n&rsquo;avez toujours pas le droit de regarder la saga Very Bad Trip aujourd&rsquo;hui<\/li>\n<li>Si vous ne savez pas ce qu&rsquo;est un Minitel<\/li>\n<li>Si vous n&rsquo;avez jamais entendu parler de Apple II, Commodore 64, IBM, Atari ou Amiga<\/li>\n<li>Si vous ne savez pas ce qu&rsquo;est un modem RTC<\/li>\n<li>Si pour vous le 3615 est un d\u00e9partement de France<\/li>\n<li>Si vous ne jurez que par des FPS ou des jeux comme Fortnite.<\/li>\n<li>Si pour vous Monkey Island est un nom de cocktail&#8230;<\/li>\n<li>ou encore si le magazine Tilt est pour vous qu&rsquo;un vieux fanzine sur les Flippers<\/li>\n<\/ul>\n<h3>Pour terminer, nous ne pouvons ici que nous attarder au diction anti-troll et anti-d\u00e9presseur naturel qui dit :<\/h3>\n<blockquote><p><span class=\"ILfuVd\">Tout homme <b>qui<\/b> dirige, <b>qui fait<\/b> quelque <b>chose<\/b>, a contre lui <b>ceux qui<\/b> voudraient <b>faire la m\u00eame chose<\/b>, <b>ceux qui<\/b> font pr\u00e9cis\u00e9ment le contraire, et surtout la grande arm\u00e9e des gens d&rsquo;autant plus s\u00e9v\u00e8res qu&rsquo;ils ne font rien du tout. <\/span><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Nous allons vous d\u00e9voiler pourquoi, m\u00eame si cet \u00e2ge l\u00e9gal n&rsquo;existe pas officiellement chez le label, le jeu 3 GEEKS pourrait \u00eatre classifi\u00e9 PEGI 30&#8230; Le label PEGI ne d\u00e9passe pas l&rsquo;\u00e2ge de 18 ans, \u00e2ge l\u00e9gal o\u00f9 s&rsquo;arr\u00eatent toutes les limites officielles. Mais chez Adipson Studio nous allons plus loin en imaginant qu&rsquo;il pourrait [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":87,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,6],"tags":[],"class_list":["post-83","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3-geeks","category-le-saviez-vous"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3Geeks class\u00e9 humoristiquement et \u00e0 notre initiative PEGI 30 - Adipson WebAgency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3Geeks class\u00e9 humoristiquement et \u00e0 notre initiative PEGI 30 - Adipson WebAgency\" \/>\n<meta property=\"og:description\" content=\"Nous allons vous d\u00e9voiler pourquoi, m\u00eame si cet \u00e2ge l\u00e9gal n&rsquo;existe pas officiellement chez le label, le jeu 3 GEEKS pourrait \u00eatre classifi\u00e9 PEGI 30&#8230; Le label PEGI ne d\u00e9passe pas l&rsquo;\u00e2ge de 18 ans, \u00e2ge l\u00e9gal o\u00f9 s&rsquo;arr\u00eatent toutes les limites officielles. Mais chez Adipson Studio nous allons plus loin en imaginant qu&rsquo;il pourrait [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/\" \/>\n<meta property=\"og:site_name\" content=\"Adipson WebAgency\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-05T13:18:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-05T13:27:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/adipson-studio.com\/wp-content\/uploads\/2021\/08\/pegi30-3geeks.jpg?fit=852%2C318&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"852\" \/>\n\t<meta property=\"og:image:height\" content=\"318\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Adipson Studio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adipson Studio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\\\/\"},\"author\":{\"name\":\"Adipson Studio\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#\\\/schema\\\/person\\\/5d13be29716904a3364d6073994ed481\"},\"headline\":\"3Geeks class\u00e9 humoristiquement et \u00e0 notre initiative PEGI 30\",\"datePublished\":\"2021-07-05T13:18:49+00:00\",\"dateModified\":\"2021-08-05T13:27:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\\\/\"},\"wordCount\":738,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adipson-studio.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/pegi30-3geeks.jpg\",\"articleSection\":[\"3 Geeks\",\"Le saviez-vous ?\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\\\/\",\"url\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\\\/\",\"name\":\"3Geeks class\u00e9 humoristiquement et \u00e0 notre initiative PEGI 30 - Adipson WebAgency\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adipson-studio.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/pegi30-3geeks.jpg\",\"datePublished\":\"2021-07-05T13:18:49+00:00\",\"dateModified\":\"2021-08-05T13:27:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adipson-studio.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/pegi30-3geeks.jpg\",\"contentUrl\":\"https:\\\/\\\/adipson-studio.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/pegi30-3geeks.jpg\",\"width\":852,\"height\":318},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/2021\\\/07\\\/05\\\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/adipson-studio.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3Geeks class\u00e9 humoristiquement et \u00e0 notre initiative PEGI 30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#website\",\"url\":\"https:\\\/\\\/adipson-studio.com\\\/\",\"name\":\"Adipson WebAgency\",\"description\":\"Votre partenaire web depuis plus de 20 ans\",\"publisher\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adipson-studio.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#organization\",\"name\":\"Adipson WebAgency\",\"url\":\"https:\\\/\\\/adipson-studio.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adipson-studio.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logosite.png\",\"contentUrl\":\"https:\\\/\\\/adipson-studio.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logosite.png\",\"width\":283,\"height\":40,\"caption\":\"Adipson WebAgency\"},\"image\":{\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adipson-studio.com\\\/#\\\/schema\\\/person\\\/5d13be29716904a3364d6073994ed481\",\"name\":\"Adipson Studio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ed85b4921ea2a5e59d63b240be84577f053b7523b3b651b34c20439bc159222?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ed85b4921ea2a5e59d63b240be84577f053b7523b3b651b34c20439bc159222?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ed85b4921ea2a5e59d63b240be84577f053b7523b3b651b34c20439bc159222?s=96&d=mm&r=g\",\"caption\":\"Adipson Studio\"},\"sameAs\":[\"https:\\\/\\\/adipson-studio.com\"],\"url\":\"https:\\\/\\\/adipson-studio.com\\\/index.php\\\/author\\\/romualdserrado_jt4cyldi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3Geeks class\u00e9 humoristiquement et \u00e0 notre initiative PEGI 30 - Adipson WebAgency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/","og_locale":"fr_FR","og_type":"article","og_title":"3Geeks class\u00e9 humoristiquement et \u00e0 notre initiative PEGI 30 - Adipson WebAgency","og_description":"Nous allons vous d\u00e9voiler pourquoi, m\u00eame si cet \u00e2ge l\u00e9gal n&rsquo;existe pas officiellement chez le label, le jeu 3 GEEKS pourrait \u00eatre classifi\u00e9 PEGI 30&#8230; Le label PEGI ne d\u00e9passe pas l&rsquo;\u00e2ge de 18 ans, \u00e2ge l\u00e9gal o\u00f9 s&rsquo;arr\u00eatent toutes les limites officielles. Mais chez Adipson Studio nous allons plus loin en imaginant qu&rsquo;il pourrait [&hellip;]","og_url":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/","og_site_name":"Adipson WebAgency","article_published_time":"2021-07-05T13:18:49+00:00","article_modified_time":"2021-08-05T13:27:00+00:00","og_image":[{"width":852,"height":318,"url":"https:\/\/i0.wp.com\/adipson-studio.com\/wp-content\/uploads\/2021\/08\/pegi30-3geeks.jpg?fit=852%2C318&ssl=1","type":"image\/jpeg"}],"author":"Adipson Studio","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Adipson Studio","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/#article","isPartOf":{"@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/"},"author":{"name":"Adipson Studio","@id":"https:\/\/adipson-studio.com\/#\/schema\/person\/5d13be29716904a3364d6073994ed481"},"headline":"3Geeks class\u00e9 humoristiquement et \u00e0 notre initiative PEGI 30","datePublished":"2021-07-05T13:18:49+00:00","dateModified":"2021-08-05T13:27:00+00:00","mainEntityOfPage":{"@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/"},"wordCount":738,"commentCount":0,"publisher":{"@id":"https:\/\/adipson-studio.com\/#organization"},"image":{"@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/#primaryimage"},"thumbnailUrl":"https:\/\/adipson-studio.com\/wp-content\/uploads\/2021\/08\/pegi30-3geeks.jpg","articleSection":["3 Geeks","Le saviez-vous ?"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/","url":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/","name":"3Geeks class\u00e9 humoristiquement et \u00e0 notre initiative PEGI 30 - Adipson WebAgency","isPartOf":{"@id":"https:\/\/adipson-studio.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/#primaryimage"},"image":{"@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/#primaryimage"},"thumbnailUrl":"https:\/\/adipson-studio.com\/wp-content\/uploads\/2021\/08\/pegi30-3geeks.jpg","datePublished":"2021-07-05T13:18:49+00:00","dateModified":"2021-08-05T13:27:00+00:00","breadcrumb":{"@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/#primaryimage","url":"https:\/\/adipson-studio.com\/wp-content\/uploads\/2021\/08\/pegi30-3geeks.jpg","contentUrl":"https:\/\/adipson-studio.com\/wp-content\/uploads\/2021\/08\/pegi30-3geeks.jpg","width":852,"height":318},{"@type":"BreadcrumbList","@id":"https:\/\/adipson-studio.com\/index.php\/2021\/07\/05\/3geeks-classe-humoristiquement-et-a-notre-initiative-pegi-30\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/adipson-studio.com\/"},{"@type":"ListItem","position":2,"name":"3Geeks class\u00e9 humoristiquement et \u00e0 notre initiative PEGI 30"}]},{"@type":"WebSite","@id":"https:\/\/adipson-studio.com\/#website","url":"https:\/\/adipson-studio.com\/","name":"Adipson WebAgency","description":"Votre partenaire web depuis plus de 20 ans","publisher":{"@id":"https:\/\/adipson-studio.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adipson-studio.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/adipson-studio.com\/#organization","name":"Adipson WebAgency","url":"https:\/\/adipson-studio.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adipson-studio.com\/#\/schema\/logo\/image\/","url":"https:\/\/adipson-studio.com\/wp-content\/uploads\/2024\/08\/logosite.png","contentUrl":"https:\/\/adipson-studio.com\/wp-content\/uploads\/2024\/08\/logosite.png","width":283,"height":40,"caption":"Adipson WebAgency"},"image":{"@id":"https:\/\/adipson-studio.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/adipson-studio.com\/#\/schema\/person\/5d13be29716904a3364d6073994ed481","name":"Adipson Studio","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2ed85b4921ea2a5e59d63b240be84577f053b7523b3b651b34c20439bc159222?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ed85b4921ea2a5e59d63b240be84577f053b7523b3b651b34c20439bc159222?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ed85b4921ea2a5e59d63b240be84577f053b7523b3b651b34c20439bc159222?s=96&d=mm&r=g","caption":"Adipson Studio"},"sameAs":["https:\/\/adipson-studio.com"],"url":"https:\/\/adipson-studio.com\/index.php\/author\/romualdserrado_jt4cyldi\/"}]}},"_links":{"self":[{"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/posts\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/comments?post=83"}],"version-history":[{"count":1,"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/posts\/83\/revisions"}],"predecessor-version":[{"id":86,"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/posts\/83\/revisions\/86"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/media\/87"}],"wp:attachment":[{"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/media?parent=83"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/categories?post=83"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adipson-studio.com\/index.php\/wp-json\/wp\/v2\/tags?post=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}